{"id":16669,"date":"2025-12-08T00:30:16","date_gmt":"2025-12-07T23:30:16","guid":{"rendered":"https:\/\/ecowood-market.com\/?post_type=product&#038;p=16669"},"modified":"2026-09-02T02:26:15","modified_gmt":"2026-09-02T00:26:15","slug":"halbe-palette-kammergetrocknetes-gespalten-birke-brennholz-25cm","status":"publish","type":"product","link":"https:\/\/fest-holz.com\/index.php\/produit\/halbe-palette-kammergetrocknetes-gespalten-birke-brennholz-25cm\/","title":{"rendered":"Halbe Palette kammergetrocknetes gespalten Birke Brennholz 25cm"},"content":{"rendered":"<h1 class=\"h3 text-base lg:text-lg font-semibold mb-3\">Beschreibung<\/h1>\n<div class=\"product-description read-more-content max-lines-8 expanded\" data-initiated=\"true\" data-expandable=\"true\">\n<div data-content-type=\"row\" data-appearance=\"contained\" data-element=\"main\">\n<div data-enable-parallax=\"0\" data-parallax-speed=\"0.5\" data-background-images=\"{}\" data-background-type=\"image\" data-video-loop=\"true\" data-video-play-only-visible=\"true\" data-video-lazy-load=\"true\" data-video-fallback-src=\"\" data-element=\"inner\" data-pb-style=\"Y0KP3DG\">\n<div data-content-type=\"text\" data-appearance=\"default\" data-element=\"main\">\n<p>Suchen Sie nach der m\u00fchelosesten Art, Ihr Brennholz anzuz\u00fcnden? Dann entdecken Sie den unvergleichlichen Komfort unseres Birkenbrennholzes in halben Paletten! Mit diesem Brennstoff wird das Anz\u00fcnden Ihres Ofens oder Kamins zu einem Kinderspiel, und Sie werden ein Brennholzerlebnis wie nie zuvor genie\u00dfen.<\/p>\n<\/div>\n<div data-content-type=\"text\" data-appearance=\"default\" data-element=\"main\">\n<p id=\"TT1PDHU\">Was macht Birkenholz so besonders? Birkenholz ist daf\u00fcr bekannt, dass es sich leicht entz\u00fcndet und nur wenig Rauch entwickelt. So genie\u00dfen Sie eine saubere und effiziente Verbrennung ohne l\u00e4stigen Rauch. Au\u00dferdem bietet Birkenholz eine sch\u00f6ne Flamme, die \u00fcberhaupt nicht knistert, so dass Sie die W\u00e4rme und die Atmosph\u00e4re in Ruhe genie\u00dfen k\u00f6nnen. Verwenden Sie zum Anz\u00fcnden Ihres Ofens reichlich damit Sie m\u00fchelos loslegen k\u00f6nnen.<\/p>\n<\/div>\n<div data-content-type=\"text\" data-appearance=\"default\" data-element=\"main\">\n<p>In den Niederlanden ist Birkenbrennholz wegen seiner sauberen Verbrennung und langen Brenndauer sehr beliebt. Unsere Halbpaletten aus Birke sind leicht zu transportieren und UV-gesch\u00fctzt, so dass sie immer in bestem Zustand bleiben. Au\u00dferdem ist unser Brennholz kammergetrocknet, was bedeutet, dass sich keine Sch\u00e4dlinge oder Schimmel auf dem Holz befinden.<\/p>\n<\/div>\n<div data-content-type=\"text\" data-appearance=\"default\" data-element=\"main\">\n<p>Kurzum, wenn Sie Brennholz suchen, das leicht zu transportieren ist, sauber brennt, nicht knistert und einfach zu verwenden ist, dann sind Sie bei uns genau richtig. Bestellen Sie noch heute unser Birken-Kaminholz in halben Paletten und erleben Sie das ultimative, problemlose Kaminerlebnis!<\/p>\n<h2 class=\"h3 text-black text-lg font-semibold leading-5 lg:text-[28px] lg:font-semibold lg:leading-8 mb-4\">Alle Spezifikationen<\/h2>\n<div id=\"product-attributes\">\n<table class=\"additional-attributes w-full text-xs md:text-sm border border-gray-300\">\n<tbody>\n<tr class=\"spec even:bg-[#F3F3F3]\">\n<td class=\"spec-label m-0 p-3 flex justify-between items-center\">SKU<\/td>\n<td class=\"spec-value p-3 text-right\">BE12000<\/td>\n<\/tr>\n<tr class=\"spec even:bg-[#F3F3F3]\">\n<td class=\"spec-label m-0 p-3 flex justify-between items-center\">Marke<\/td>\n<td class=\"spec-value p-3 text-right\">Eigenmarke<\/td>\n<\/tr>\n<tr class=\"spec even:bg-[#F3F3F3]\">\n<td class=\"spec-label m-0 p-3 flex justify-between items-center\">Verpackung<\/td>\n<td class=\"spec-value p-3 text-right\">120 cm x 85 cm x 100 cm<\/td>\n<\/tr>\n<tr class=\"spec even:bg-[#F3F3F3]\">\n<td class=\"spec-label m-0 p-3 flex justify-between items-center\">H\u00f6he<\/td>\n<td class=\"spec-value p-3 text-right\">120 cm<\/td>\n<\/tr>\n<tr class=\"spec even:bg-[#F3F3F3]\">\n<td class=\"spec-label m-0 p-3 flex justify-between items-center\">Breite<\/td>\n<td class=\"spec-value p-3 text-right\">85 cm<\/td>\n<\/tr>\n<tr class=\"spec even:bg-[#F3F3F3]\">\n<td class=\"spec-label m-0 p-3 flex justify-between items-center\">L\u00e4nge<\/td>\n<td class=\"spec-value p-3 text-right\">100 cm<\/td>\n<\/tr>\n<tr class=\"spec even:bg-[#F3F3F3]\">\n<td class=\"spec-label m-0 p-3 flex justify-between items-center\">Gewicht<\/td>\n<td class=\"spec-value p-3 text-right\">375 kg<\/td>\n<\/tr>\n<tr class=\"spec even:bg-[#F3F3F3]\">\n<td class=\"spec-label m-0 p-3 flex justify-between items-center\">Inhalt<\/td>\n<td class=\"spec-value p-3 text-right\">0,9 RM<\/td>\n<\/tr>\n<tr class=\"spec even:bg-[#F3F3F3]\">\n<td class=\"spec-label m-0 p-3 flex justify-between items-center\">Brennholz Arten<\/td>\n<td class=\"spec-value p-3 text-right\">Brennholz Birken<\/td>\n<\/tr>\n<tr class=\"spec even:bg-[#F3F3F3]\">\n<td class=\"spec-label m-0 p-3 flex justify-between items-center\">Restfeuchte<\/td>\n<td class=\"spec-value p-3 text-right\">&lt; 20%<\/td>\n<\/tr>\n<tr class=\"spec even:bg-[#F3F3F3]\">\n<td class=\"spec-label m-0 p-3 flex justify-between items-center\">Scheitl\u00e4nge<\/td>\n<td class=\"spec-value p-3 text-right\">23\/25 cm<\/td>\n<\/tr>\n<tr class=\"spec even:bg-[#F3F3F3]\">\n<td class=\"spec-label m-0 p-3 flex justify-between items-center\">Abschnitt<\/td>\n<td class=\"spec-value p-3 text-right\">8 bis 12 cm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Beschreibung Suchen Sie nach der m\u00fchelosesten Art, Ihr Brennholz anzuz\u00fcnden? Dann entdecken Sie den unvergleichlichen Komfort unseres Birkenbrennholzes in halben<\/p>\n","protected":false},"featured_media":16670,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[224],"product_tag":[],"class_list":{"0":"post-16669","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-birke-brennholz","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/product\/16669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/comments?post=16669"}],"version-history":[{"count":1,"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/product\/16669\/revisions"}],"predecessor-version":[{"id":16674,"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/product\/16669\/revisions\/16674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/media\/16670"}],"wp:attachment":[{"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/media?parent=16669"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=16669"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=16669"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=16669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}