{"id":15730,"date":"2025-11-20T13:16:25","date_gmt":"2025-11-20T12:16:25","guid":{"rendered":"https:\/\/ecowood-market.com\/?post_type=product&#038;p=15730"},"modified":"2026-09-02T02:26:18","modified_gmt":"2026-09-02T00:26:18","slug":"palette-mit-15-raummetern-holz-in-50-cm-mischung-aus-hartholzern-buche-eiche-hainbuche","status":"publish","type":"product","link":"https:\/\/fest-holz.com\/index.php\/produit\/palette-mit-15-raummetern-holz-in-50-cm-mischung-aus-hartholzern-buche-eiche-hainbuche\/","title":{"rendered":"Palette mit 1,5 Raummetern Holz in 50 cm \u2013 Mischung aus Harth\u00f6lzern (Buche, Eiche, Hainbuche)"},"content":{"rendered":"<p>Unsere Brennholzscheite garantieren Ihnen eine optimale Energieausbeute, eine effiziente Verbrennung und eine optimale W\u00e4rmeabgabe. Sie eignen sich perfekt f\u00fcr eine hochwertige Heizung und sorgen f\u00fcr eine gleichm\u00e4\u00dfige und angenehme W\u00e4rme.<\/p>\n<p>Sie sind praktisch in der Handhabung und dank ihrer Palettenverpackung leicht zu lagern.<br \/>\nProfitieren Sie von Ihren 50 cm langen Brennholzscheiten<br \/>\nDie Mischung besteht ausschlie\u00dflich aus Buche, Hainbuche und Eiche, den Holzarten mit dem h\u00f6chsten Heizwert f\u00fcr Brennholz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Palette mit 1,5 Raummetern gestapeltem Brennholz.<\/p>\n<p>Die Palette besteht aus Hartholz, das zu den Holzarten mit dem h\u00f6chsten Heizwert geh\u00f6rt: Buche, Eiche und Hainbuche.<\/p>\n<p>Gewicht:<br \/>\n650 kg<br \/>\nGr\u00f6\u00dfe:<br \/>\nScheite 50 cm<br \/>\nVerpackung:<br \/>\n1 Palette = 1,5 Raummeter<\/p>\n","protected":false},"featured_media":15733,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[75],"product_tag":[],"class_list":{"0":"post-15730","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-brennholz","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/product\/15730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/comments?post=15730"}],"version-history":[{"count":1,"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/product\/15730\/revisions"}],"predecessor-version":[{"id":15734,"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/product\/15730\/revisions\/15734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/media\/15733"}],"wp:attachment":[{"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/media?parent=15730"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=15730"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=15730"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fest-holz.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=15730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}